{"id":2108,"date":"2025-11-29T23:42:32","date_gmt":"2025-11-29T22:42:32","guid":{"rendered":"http:\/\/wp1.iesagora.es:60010\/creagora\/?p=2108"},"modified":"2025-12-11T23:08:33","modified_gmt":"2025-12-11T22:08:33","slug":"proyecto-luz-de-los-recuerdos","status":"publish","type":"post","link":"http:\/\/wp1.iesagora.es:60010\/creagora\/2025\/11\/29\/proyecto-luz-de-los-recuerdos\/","title":{"rendered":"Proyecto \u00ab\u00a1Gira y Gana!\u00bb"},"content":{"rendered":"\n<p>Somos <strong>Guadalupe G\u00f3mez Isidoro y Pedro Fern\u00e1ndez S\u00e1nchez<\/strong> , estudiantes de segundo curso del <strong>Grado Superior en Gesti\u00f3n de Ventas y Espacios Comerciales<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/12\/PHOTO-2025-10-22-14-03-55-edited-768x1024.jpg\" alt=\"\" class=\"wp-image-2633\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/12\/PHOTO-2025-10-22-14-03-55-edited-768x1024.jpg 768w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/12\/PHOTO-2025-10-22-14-03-55-edited-225x300.jpg 225w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/12\/PHOTO-2025-10-22-14-03-55-edited-600x800.jpg 600w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/12\/PHOTO-2025-10-22-14-03-55-edited.jpg 1056w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"500\" height=\"500\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-51.png\" alt=\"\" class=\"wp-image-2333\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-51.png 500w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-51-300x300.png 300w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-51-150x150.png 150w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-51-100x100.png 100w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-text-align-center\"><strong>En Que consiste Nuestra idea?<\/strong><\/p>\n\n\n\n<p>Nuestra empresa, \u00abGIRA Y GANA\u00bb, se dedica a la organizaci\u00f3n de experiencias interactivas de entretenimiento y promoci\u00f3n a trav\u00e9s de una <strong>ruleta de premios<\/strong>, as\u00ed como a la venta de <strong>bolsas tem\u00e1ticas para regalar<\/strong>.<\/p>\n\n\n\n<p><strong>Nuestros productos principales son:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ruleta de la suerte:<\/strong> Una actividad din\u00e1mica con premios peque\u00f1os y llamativos (llaveros, bolis, pulseras, etc.). El precio por tirada es de <strong>1,00 \u20ac<\/strong>.<\/li>\n\n\n\n<li><strong>Kit de Netflix:<\/strong> Bolsas dise\u00f1adas en torno a tem\u00e1ticas populares que incluyen una selecci\u00f3n de productos como golosinas y peque\u00f1os regalos. El precio de venta del kit es de <strong>3,00 \u20ac<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"2414\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1-768x1024.jpg\" alt=\"\" class=\"wp-image-2414\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1-768x1024.jpg 768w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1-225x300.jpg 225w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1-1152x1536.jpg 1152w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1-600x800.jpg 600w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-05-a-las-13.27.39_f53438ae-1.jpg 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"435\" height=\"650\" data-id=\"2339\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-54.png\" alt=\"\" class=\"wp-image-2339\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-54.png 435w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-54-201x300.png 201w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"391\" height=\"413\" data-id=\"2334\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-52.png\" alt=\"\" class=\"wp-image-2334\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-52.png 391w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-52-284x300.png 284w\" sizes=\"(max-width: 391px) 100vw, 391px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Nuestra inversi\u00f3n<\/strong><\/p>\n\n\n\n<p>Cada miembro del grupo ha aportado un total de 30\u20ac, que recuperaremos con las ventas de este primer trimestre. El beneficio excedente ser\u00e1 destinado a financiar una actividad<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>An\u00e1lisis del mercado<\/strong><\/p>\n\n\n\n<p>Hemos estudiado el mercado al que nos dirigimos, el cual, seg\u00fan informaci\u00f3n del jefe de estudios del centro, est\u00e1 compuesto por un total de 1.197 personas<\/p>\n\n\n\n<p>El grupo m\u00e1s grande es el de los alumnos, que representa un 86,8% (1.039 estudiantes).<\/p>\n\n\n\n<p>Los profesores suponen el 11,9% (143 docentes).<\/p>\n\n\n\n<p>El personal no docente ocupa el 1,3% restante<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"459\" data-id=\"2597\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-89.png\" alt=\"\" class=\"wp-image-2597\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-89.png 620w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-89-300x222.png 300w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-89-600x444.png 600w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"468\" data-id=\"2596\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-88.png\" alt=\"\" class=\"wp-image-2596\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-88.png 623w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-88-300x225.png 300w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/image-88-600x451.png 600w\" sizes=\"(max-width: 623px) 100vw, 623px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>El segmento   <\/strong>     <\/p>\n\n\n\n<p class=\"has-text-align-left\">que hemos elegido para comercializar nuestro producto son alumnos de 10-17 a\u00f1os que disfrutan de las golosinas y de pasar una tarde de pel\u00edculas con amigos o familia. Buscan diversi\u00f3n y experiencias entretenidas &nbsp;y cuentan con un presupuesto de dinero de bolsillo para gastos peque\u00f1os. <\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Escaparate<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-1024x768.jpg\" alt=\"\" class=\"wp-image-2602\" srcset=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-1024x768.jpg 1024w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-300x225.jpg 300w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-768x576.jpg 768w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-1536x1152.jpg 1536w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59-600x450.jpg 600w, http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/Imagen-de-WhatsApp-2025-12-09-a-las-13.36.05_4552ed59.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>Plan De Ventas<\/strong><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/plan-de-ventas-Guadalupe-y-Pedro.pdf\" type=\"application\/pdf\" style=\"width:100%;height:790px\" aria-label=\"Incrustado de plan de ventas Guadalupe y Pedro.\"><\/object><a id=\"wp-block-file--media-6f97d849-89fe-45ce-a70e-539ae77b4ab8\" href=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/plan-de-ventas-Guadalupe-y-Pedro.pdf\">plan de ventas Guadalupe y Pedro<\/a><a href=\"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/plan-de-ventas-Guadalupe-y-Pedro.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-6f97d849-89fe-45ce-a70e-539ae77b4ab8\">Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Somos Guadalupe G\u00f3mez Isidoro y Pedro Fern\u00e1ndez S\u00e1nchez , estudiantes de segundo curso del Grado Superior en Gesti\u00f3n de Ventas [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":2332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6,54,3],"tags":[69],"class_list":["post-2108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1o-gvec","category-campana-de-ventas","category-mercado-de-navidad","tag-25_26_guadalupe_fernandez"],"jetpack_featured_media_url":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-content\/uploads\/sites\/172\/2025\/11\/PHOTO-2025-10-22-14-03-55.jpg","_links":{"self":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/posts\/2108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/comments?post=2108"}],"version-history":[{"count":18,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/posts\/2108\/revisions"}],"predecessor-version":[{"id":2635,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/posts\/2108\/revisions\/2635"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/media\/2332"}],"wp:attachment":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/media?parent=2108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/categories?post=2108"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/tags?post=2108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}