{"id":57,"count":6,"description":"","link":"http:\/\/wp1.iesagora.es:60010\/creagora\/category\/campana-de-ventas\/estudio-de-mercado\/","name":"Estudio de Mercado","slug":"estudio-de-mercado","taxonomy":"category","parent":54,"meta":[],"_links":{"self":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/categories\/57","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/categories\/54"}],"wp:post_type":[{"href":"http:\/\/wp1.iesagora.es:60010\/creagora\/wp-json\/wp\/v2\/posts?categories=57"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}